{"id":782,"date":"2024-03-30T13:38:11","date_gmt":"2024-03-30T13:38:11","guid":{"rendered":"https:\/\/feuerwehr-nordsehl-lauenhagen.de\/?p=782"},"modified":"2024-03-30T13:38:11","modified_gmt":"2024-03-30T13:38:11","slug":"osterfeuer-2024-wir-sind-startklar","status":"publish","type":"post","link":"https:\/\/feuerwehr-nordsehl-lauenhagen.de\/index.php\/2024\/03\/30\/osterfeuer-2024-wir-sind-startklar\/","title":{"rendered":"Osterfeuer 2024 &#8211; Wir sind startklar!"},"content":{"rendered":"<p>Die Vorbereitungen sind abgeschlossen und wir freuen uns auf einen sch\u00f6nen gemeinsamen Abend mit euch.<\/p>\n<p>Los geht es um 18:30 Uhr mit dem Fackelumzug vom Westerfeld in Lauenhagen zur Feuerwache Nordsehl-Lauenhagen. Hier entz\u00fcnden wir gemeinsam das Kinderfeuer.<\/p>\n<p>Vor Ort erwarten euch neben den bew\u00e4hrten Leckereien am Grill und einer gro\u00dfen Auswahl an erfrischenden Getr\u00e4nken auch ein Cr\u00eapes-Stand, k\u00f6stliche Fischbr\u00f6tchen und handgemachtes Stockbrot.<\/p>\n<p>In diesem Jahr gibt es wieder die M\u00f6glichkeit in der Fahrzeughalle zu sitzen.<\/p>\n<p>!!!WICHTIG!!!<\/p>\n<p>In der N\u00e4he vom Osterfeuer ist der Boden leider noch nass. Hier ist es empfehlenswert festes Schuhwerk oder Gummistiefel anzuziehen.<\/p>\n<p>Um 19:00 Uhr geht es los. Wir freuen uns auf euch <span class=\"x1xsqp64 xiy17q3 x1o6pynw x19co3pv xdj266r xcwd3tp xat24cr x39eecv x2b8uid\" data-testid=\"emoji\"><span class=\"xexx8yu xn5pp95 x18d9i69 x2fxd7x x1yqt14a x1bhl96m\">\ud83d\ude42<\/span><\/span><\/p>\n<p><a href=\"https:\/\/feuerwehr-nordsehl-lauenhagen.de\/wp-content\/uploads\/2024\/03\/20240330_140616-1-scaled.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-783 size-large\" src=\"https:\/\/feuerwehr-nordsehl-lauenhagen.de\/wp-content\/uploads\/2024\/03\/20240330_140616-1-1024x1024.jpg\" alt=\"\" width=\"640\" height=\"640\" srcset=\"https:\/\/feuerwehr-nordsehl-lauenhagen.de\/wp-content\/uploads\/2024\/03\/20240330_140616-1-1024x1024.jpg 1024w, https:\/\/feuerwehr-nordsehl-lauenhagen.de\/wp-content\/uploads\/2024\/03\/20240330_140616-1-300x300.jpg 300w, https:\/\/feuerwehr-nordsehl-lauenhagen.de\/wp-content\/uploads\/2024\/03\/20240330_140616-1-150x150.jpg 150w, https:\/\/feuerwehr-nordsehl-lauenhagen.de\/wp-content\/uploads\/2024\/03\/20240330_140616-1-768x768.jpg 768w, https:\/\/feuerwehr-nordsehl-lauenhagen.de\/wp-content\/uploads\/2024\/03\/20240330_140616-1-1536x1536.jpg 1536w, https:\/\/feuerwehr-nordsehl-lauenhagen.de\/wp-content\/uploads\/2024\/03\/20240330_140616-1-2048x2048.jpg 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Vorbereitungen sind abgeschlossen und wir freuen uns auf einen sch\u00f6nen gemeinsamen Abend mit euch. Los geht es um 18:30 Uhr mit dem Fackelumzug vom Westerfeld in Lauenhagen zur Feuerwache Nordsehl-Lauenhagen. Hier entz\u00fcnden wir gemeinsam das Kinderfeuer. Vor Ort erwarten &hellip; <a href=\"https:\/\/feuerwehr-nordsehl-lauenhagen.de\/index.php\/2024\/03\/30\/osterfeuer-2024-wir-sind-startklar\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-782","post","type-post","status-publish","format-standard","hentry","category-termine"],"_links":{"self":[{"href":"https:\/\/feuerwehr-nordsehl-lauenhagen.de\/index.php\/wp-json\/wp\/v2\/posts\/782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feuerwehr-nordsehl-lauenhagen.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/feuerwehr-nordsehl-lauenhagen.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/feuerwehr-nordsehl-lauenhagen.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/feuerwehr-nordsehl-lauenhagen.de\/index.php\/wp-json\/wp\/v2\/comments?post=782"}],"version-history":[{"count":1,"href":"https:\/\/feuerwehr-nordsehl-lauenhagen.de\/index.php\/wp-json\/wp\/v2\/posts\/782\/revisions"}],"predecessor-version":[{"id":784,"href":"https:\/\/feuerwehr-nordsehl-lauenhagen.de\/index.php\/wp-json\/wp\/v2\/posts\/782\/revisions\/784"}],"wp:attachment":[{"href":"https:\/\/feuerwehr-nordsehl-lauenhagen.de\/index.php\/wp-json\/wp\/v2\/media?parent=782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feuerwehr-nordsehl-lauenhagen.de\/index.php\/wp-json\/wp\/v2\/categories?post=782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/feuerwehr-nordsehl-lauenhagen.de\/index.php\/wp-json\/wp\/v2\/tags?post=782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}